{"id":3552,"date":"2024-09-26T11:39:12","date_gmt":"2024-09-26T14:39:12","guid":{"rendered":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/?p=3552"},"modified":"2024-10-31T16:49:19","modified_gmt":"2024-10-31T19:49:19","slug":"cientificos-por-un-dia","status":"publish","type":"post","link":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/cientificos-por-un-dia\/","title":{"rendered":"Cient\u00edfico por un d\u00eda"},"content":{"rendered":"\n<p>Los pr\u00f3ximos <strong>30 de septiembre y 1 de octubre<\/strong>, se llevar\u00e1 a cabo la actividad <strong>\u00abCient\u00edfico por un d\u00eda\u00bb<\/strong> en las instalaciones del <strong>Instituto de Formaci\u00f3n Docente y T\u00e9cnica N\u00ba 9-006 \u00abProfesor Francisco Humberto Tolosa\u00bb<\/strong>, con horarios de <strong>9:00 a 12:30<\/strong> y <strong>14:00 a 18:00<\/strong>.<\/p>\n\n\n\n<p>Este encuentro cient\u00edfico, que se ha consolidado a lo largo de los a\u00f1os, re\u00fane a <strong>estudiantes y docentes<\/strong> con el objetivo de <strong>divulgar las ciencias b\u00e1sicas<\/strong> y fomentar espacios de <strong>encuentro y debate<\/strong>. Adem\u00e1s, la jornada busca crear instancias de <strong>ense\u00f1anza-aprendizaje<\/strong> diferentes a las tradicionales del aula, promoviendo el <strong>intercambio de ideas<\/strong> entre estudiantes de todos los niveles educativos.<\/p>\n\n\n\n<p>La actividad \u00abCient\u00edfico por un d\u00eda\u00bb es una oportunidad \u00fanica para aprender, compartir y reflexionar sobre el papel de la ciencia en la educaci\u00f3n y en la sociedad.<\/p>\n\n\n\n<p>\u00a1No te pierdas esta jornada de ciencia y aprendizaje colaborativo!<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" loading=\"lazy\" width=\"1040\" height=\"780\" data-id=\"3603\"  src=\"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-2.jpg\" alt=\"\" class=\"wp-image-3603\" srcset=\"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-2.jpg 1040w, https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-2-1000x750.jpg 1000w, https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-2-768x576.jpg 768w\" sizes=\"(max-width: 1040px) 100vw, 1040px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" loading=\"lazy\" width=\"1600\" height=\"900\" data-id=\"3604\"  src=\"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-3.jpg\" alt=\"\" class=\"wp-image-3604\" srcset=\"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-3.jpg 1600w, https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-3-1000x563.jpg 1000w, https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-3-768x432.jpg 768w, https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-3-1536x864.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" loading=\"lazy\" width=\"1600\" height=\"900\" data-id=\"3605\"  src=\"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-4.jpg\" alt=\"\" class=\"wp-image-3605\" srcset=\"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-4.jpg 1600w, https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-4-1000x563.jpg 1000w, https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-4-768x432.jpg 768w, https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-4-1536x864.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" loading=\"lazy\" width=\"1600\" height=\"1200\" data-id=\"3606\"  src=\"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-5.jpg\" alt=\"\" class=\"wp-image-3606\" srcset=\"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-5.jpg 1600w, https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-5-1000x750.jpg 1000w, https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-5-768x576.jpg 768w, https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-5-1536x1152.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" loading=\"lazy\" width=\"1600\" height=\"1200\" data-id=\"3607\"  src=\"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-6.jpg\" alt=\"\" class=\"wp-image-3607\" srcset=\"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-6.jpg 1600w, https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-6-1000x750.jpg 1000w, https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-6-768x576.jpg 768w, https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/09\/cientifico-2024-6-1536x1152.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" loading=\"lazy\" width=\"1040\" height=\"780\" data-id=\"3601\"  src=\"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/10\/cientifico-2024-1.jpg\" alt=\"\" class=\"wp-image-3601\" srcset=\"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/10\/cientifico-2024-1.jpg 1040w, https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/10\/cientifico-2024-1-1000x750.jpg 1000w, https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-content\/uploads\/2024\/10\/cientifico-2024-1-768x576.jpg 768w\" sizes=\"(max-width: 1040px) 100vw, 1040px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Los pr\u00f3ximos 30 de septiembre y 1 de octubre, se llevar\u00e1 a cabo la actividad \u00abCient\u00edfico por un d\u00eda\u00bb en las instalaciones del Instituto de Formaci\u00f3n Docente y T\u00e9cnica N\u00ba 9-006 \u00abProfesor Francisco Humberto Tolosa\u00bb, con horarios de 9:00 a 12:30 y 14:00 a 18:00. Este encuentro cient\u00edfico, que se ha consolidado a lo largo &#8230; <a title=\"Cient\u00edfico por un d\u00eda\" class=\"read-more\" href=\"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/cientificos-por-un-dia\/\" aria-label=\"More on Cient\u00edfico por un d\u00eda\">[+]<\/a><\/p>\n","protected":false},"author":1406,"featured_media":3553,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7,6],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/3552"}],"collection":[{"href":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/users\/1406"}],"replies":[{"embeddable":true,"href":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/comments?post=3552"}],"version-history":[{"count":6,"href":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/3552\/revisions"}],"predecessor-version":[{"id":3660,"href":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/3552\/revisions\/3660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/media\/3553"}],"wp:attachment":[{"href":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/media?parent=3552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/categories?post=3552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/tags?post=3552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}