{"id":3597,"date":"2024-10-03T14:45:14","date_gmt":"2024-10-03T17:45:14","guid":{"rendered":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/?p=3597"},"modified":"2024-10-03T15:38:58","modified_gmt":"2024-10-03T18:38:58","slug":"observacion-del-eclipse-parcial-de-sol","status":"publish","type":"post","link":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/observacion-del-eclipse-parcial-de-sol\/","title":{"rendered":"Observaci\u00f3n del Eclipse Parcial de Sol"},"content":{"rendered":"\n<p>El 2 de octubre, en los jardines de la Biblioteca estudiantes y profesores se reunieron para  observar el eclipse parcial de Sol. La actividad, se llev\u00f3 a cabo de 16:00 a 18:30 horas, y tuvo su m\u00e1ximo ocultamiento a las 17:27 horas.<\/p>\n\n\n\n<p>Organizada por la profesora Minelli, esta jornada brind\u00f3 a los asistentes la oportunidad de disfrutar y aprender sobre este fascinante fen\u00f3meno astron\u00f3mico en un entorno natural. Agradecemos a todos los que se sumaron a esta experiencia \u00fanica.<\/p>\n\n\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fpermalink.php%3Fstory_fbid%3Dpfbid033UwGs8cMpujFf5f5BL1N1nHUDqYFKEvuqPmVXsWiF6kGNtXsZJwBGMsTMweA7XqVl%26id%3D100064031160826&amp;show_text=true&amp;width=500\" width=\"500\" height=\"582\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 2 de octubre, en los jardines de la Biblioteca estudiantes y profesores se reunieron para observar el eclipse parcial de Sol. La actividad, se llev\u00f3 a cabo de 16:00 a 18:30 horas, y tuvo su m\u00e1ximo ocultamiento a las 17:27 horas. Organizada por la profesora Minelli, esta jornada brind\u00f3 a los asistentes la oportunidad &#8230; <a title=\"Observaci\u00f3n del Eclipse Parcial de Sol\" class=\"read-more\" href=\"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/observacion-del-eclipse-parcial-de-sol\/\" aria-label=\"More on Observaci\u00f3n del Eclipse Parcial de Sol\">[+]<\/a><\/p>\n","protected":false},"author":1406,"featured_media":3598,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7,6],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/3597"}],"collection":[{"href":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/users\/1406"}],"replies":[{"embeddable":true,"href":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/comments?post=3597"}],"version-history":[{"count":2,"href":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/3597\/revisions"}],"predecessor-version":[{"id":3630,"href":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/posts\/3597\/revisions\/3630"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/media\/3598"}],"wp:attachment":[{"href":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/media?parent=3597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/categories?post=3597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ens9006-infd.mendoza.edu.ar\/sitio\/wp-json\/wp\/v2\/tags?post=3597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}